{"id":668,"date":"2023-07-21T23:59:41","date_gmt":"2023-07-21T23:59:41","guid":{"rendered":"https:\/\/chemuza.org\/pt\/o-aco-e-um-composto\/"},"modified":"2023-07-21T23:59:41","modified_gmt":"2023-07-21T23:59:41","slug":"o-aco-e-um-composto","status":"publish","type":"post","link":"https:\/\/chemuza.org\/pt\/o-aco-e-um-composto\/","title":{"rendered":"O a\u00e7o \u00e9 um composto? (+3 fatos para saber)"},"content":{"rendered":"<p><strong>N\u00e3o, o a\u00e7o n\u00e3o \u00e9 um <a href=\"https:\/\/chemuza.org\/pt\/definicoes-basicas-de-quimica\/\">composto<\/a> . O a\u00e7o \u00e9 uma liga que \u00e9 uma <a href=\"https:\/\/chemuza.org\/pt\/definicoes-basicas-de-quimica\/\">mistura<\/a> de <a href=\"https:\/\/chemuza.org\/pt\/definicoes-basicas-de-quimica\/\">ferro<\/a> e <a href=\"https:\/\/chemuza.org\/pt\/definicoes-basicas-de-quimica\/\">carbono<\/a> , al\u00e9m de outros elementos como mangan\u00eas, cromo ou n\u00edquel.<\/strong> <strong>Ao contr\u00e1rio dos compostos, as ligas s\u00e3o formadas pela mistura e solidifica\u00e7\u00e3o de diferentes elementos sem sofrer rea\u00e7\u00e3o qu\u00edmica.<\/strong><\/p>\n<p> Bem, essa foi apenas uma resposta simples. Mas h\u00e1 mais algumas coisas que voc\u00ea deve saber sobre esse assunto que deixar\u00e3o seu conceito muito claro.<\/p>\n<p> Ent\u00e3o, vamos direto ao assunto. <\/p>\n<div class=\"inherit-container-width wp-block-group key is-layout-constrained wp-block-group-is-layout-constrained\">\n<div class=\"wp-block-group__inner-container\">\n<h3 class=\"wp-block-heading\"> <strong>Principais conclus\u00f5es: o a\u00e7o \u00e9 um composto?<\/strong><\/h3>\n<ul>\n<li> O a\u00e7o n\u00e3o \u00e9 um composto, mas uma liga, que \u00e9 uma mistura de ferro e carbono, al\u00e9m de outros elementos.<\/li>\n<li> O a\u00e7o \u00e9 uma mistura homog\u00eanea, o que significa que seus componentes est\u00e3o distribu\u00eddos uniformemente em n\u00edvel at\u00f4mico ou molecular.<\/li>\n<li> Ao contr\u00e1rio dos compostos, os <a href=\"https:\/\/chemuza.org\/pt\/definicoes-basicas-de-quimica\/\">elementos<\/a> do a\u00e7o n\u00e3o sofrem rea\u00e7\u00f5es qu\u00edmicas, mas ret\u00eam as suas propriedades individuais.<\/li>\n<\/ul>\n<\/div>\n<\/div>\n<h2 class=\"wp-block-heading\"> <strong>Por que o a\u00e7o \u00e9 uma mistura?<\/strong><\/h2>\n<p class=\"ans\"> <em>O a\u00e7o \u00e9 considerado uma mistura porque \u00e9 composto por v\u00e1rios elementos ou compostos. Mais especificamente, o a\u00e7o \u00e9 composto principalmente de ferro e carbono, com pequenas quantidades de outros elementos adicionados para melhorar as suas propriedades. Esta combina\u00e7\u00e3o de diferentes componentes confere ao a\u00e7o caracter\u00edsticas e versatilidade \u00fanicas.<\/em><\/p>\n<p> Mais detalhadamente, o a\u00e7o \u00e9 uma liga, o que significa que \u00e9 uma mistura de dois ou mais elementos, geralmente metais. Os principais componentes do a\u00e7o s\u00e3o o ferro e o carbono. O ferro proporciona resist\u00eancia e integridade estrutural, enquanto o carbono ajuda a melhorar a dureza e outras propriedades mec\u00e2nicas.<\/p>\n<p> Por\u00e9m, o a\u00e7o tamb\u00e9m pode conter outros elementos como mangan\u00eas, cromo, n\u00edquel e molibd\u00eanio, entre outros. Esses elementos adicionais s\u00e3o frequentemente adicionados em pequenas quantidades para melhorar propriedades espec\u00edficas do a\u00e7o, como resist\u00eancia \u00e0 corros\u00e3o, resist\u00eancia ao calor ou aumento de resist\u00eancia.<\/p>\n<p> A mistura desses elementos ao a\u00e7o produz uma ampla gama de tipos de a\u00e7o com propriedades e aplica\u00e7\u00f5es variadas. Diferentes combina\u00e7\u00f5es e propor\u00e7\u00f5es de elementos resultam em a\u00e7os com diferentes resist\u00eancias, ductilidades e outras caracter\u00edsticas.<\/p>\n<p> Essa versatilidade torna o a\u00e7o um dos materiais mais utilizados em diversos setores, incluindo constru\u00e7\u00e3o, automotivo, aeroespacial e manufatura. A capacidade de adaptar a composi\u00e7\u00e3o do a\u00e7o para atender a requisitos espec\u00edficos \u00e9 um fator chave na sua ampla utiliza\u00e7\u00e3o e import\u00e2ncia na sociedade moderna.<\/p>\n<h2 class=\"wp-block-heading\"> <strong>Que tipo de mistura \u00e9 o a\u00e7o?<\/strong><\/h2>\n<p class=\"ans\"> <em>O a\u00e7o \u00e9 uma mistura homog\u00eanea.<\/em> <em>Parece totalmente uniforme, tanto em sua estrutura macrosc\u00f3pica quanto microsc\u00f3pica. Isto significa que os componentes, como ferro, carbono e outros elementos de liga, est\u00e3o distribu\u00eddos uniformemente em n\u00edvel at\u00f4mico ou molecular.<\/em><\/p>\n<p> Numa mistura homog\u00eanea, os componentes s\u00e3o distribu\u00eddos uniformemente e n\u00e3o podem ser facilmente distinguidos ou separados visualmente. \u00c9 o caso do a\u00e7o. Quando olhamos para uma pe\u00e7a de a\u00e7o, ela parece ter composi\u00e7\u00e3o e textura consistentes. Quer seja uma amostra pequena ou um grande componente estrutural, as propriedades e a composi\u00e7\u00e3o permanecem relativamente uniformes.<\/p>\n<p> A n\u00edvel microsc\u00f3pico, o a\u00e7o consiste numa estrutura cristalina composta por \u00e1tomos de ferro com \u00e1tomos de carbono intercalados entre eles. Os \u00e1tomos de carbono ocupam os locais intersticiais na rede de ferro, criando uma solu\u00e7\u00e3o s\u00f3lida. Os elementos de liga, se presentes, tamb\u00e9m est\u00e3o uniformemente dispersos no n\u00edvel at\u00f4mico.<\/p>\n<p> A homogeneidade do a\u00e7o \u00e9 crucial para suas propriedades e desempenho. Garante resist\u00eancia mec\u00e2nica consistente, dureza e outras caracter\u00edsticas desejadas em todo o material.<\/p>\n<p> Esta uniformidade permite que engenheiros e fabricantes confiem no comportamento previs\u00edvel do a\u00e7o, tornando-o um material essencial para uma ampla gama de aplica\u00e7\u00f5es.<\/p>\n<h2 class=\"wp-block-heading\"> <strong>Por que o a\u00e7o n\u00e3o \u00e9 um composto?<\/strong><\/h2>\n<p class=\"ans\"> <em>O a\u00e7o n\u00e3o \u00e9 considerado um composto porque n\u00e3o \u00e9 composto de \u00e1tomos de diferentes elementos ligados quimicamente. Pelo contr\u00e1rio, \u00e9 uma liga que \u00e9 uma mistura de dois ou mais elementos, geralmente metais. Os componentes do a\u00e7o, como ferro e carbono, mant\u00eam suas propriedades individuais e n\u00e3o sofrem rea\u00e7\u00e3o qu\u00edmica para formar uma nova subst\u00e2ncia.<\/em><\/p>\n<p> Para ir mais longe, um composto \u00e9 formado quando \u00e1tomos de diferentes elementos se combinam quimicamente atrav\u00e9s de liga\u00e7\u00f5es qu\u00edmicas. Num composto, os \u00e1tomos s\u00e3o reorganizados e partilham electr\u00f5es para formar novas entidades qu\u00edmicas com propriedades distintas das dos elementos originais.<\/p>\n<p> Contudo, no a\u00e7o, os \u00e1tomos de ferro e carbono n\u00e3o se ligam para formar um novo composto. Em vez disso, eles coexistem como entidades separadas dentro da mistura, com o carbono ocupando os espa\u00e7os intersticiais da rede cristalina do ferro.<\/p>\n<p> A presen\u00e7a de m\u00faltiplos elementos no a\u00e7o permite que suas propriedades sejam manipuladas ajustando a composi\u00e7\u00e3o. Ao controlar a quantidade de carbono e outros elementos de liga, os engenheiros podem adaptar a resist\u00eancia, a dureza, a ductilidade e outras caracter\u00edsticas do a\u00e7o para atender a requisitos espec\u00edficos.<\/p>\n<p> Essa capacidade de alterar a composi\u00e7\u00e3o sem sofrer rea\u00e7\u00e3o qu\u00edmica \u00e9 uma caracter\u00edstica definidora das misturas, distinguindo-as dos compostos.<\/p>\n<h3 class=\"wp-block-heading\"> <strong>Leitura adicional<\/strong><\/h3>\n<p> <a href=\"https:\/\/chemuza.org\/pt\/quando-existe-um-composto\/\">O ouro \u00e9 um composto?<\/a><br \/> <a href=\"https:\/\/chemuza.org\/pt\/o-bronze-e-um-elemento\/\">O bronze \u00e9 um elemento?<\/a><br \/> <a href=\"https:\/\/chemuza.org\/pt\/o-latao-e-um-elemento\/\">O lat\u00e3o \u00e9 um elemento?<\/a><br \/> <a href=\"https:\/\/chemuza.org\/pt\/o-aluminio-e-um-condutor\/\">Por que o alum\u00ednio \u00e9 condutor?<\/a><br \/> <a href=\"https:\/\/chemuza.org\/pt\/o-cobre-e-um-condutor\/\">O cobre \u00e9 um condutor?<\/a><\/p>\n","protected":false},"excerpt":{"rendered":"<p>N\u00e3o, o a\u00e7o n\u00e3o \u00e9 um composto . O a\u00e7o \u00e9 uma liga que \u00e9 uma mistura de ferro e carbono , al\u00e9m de outros elementos como mangan\u00eas, cromo ou n\u00edquel. Ao contr\u00e1rio dos compostos, as ligas s\u00e3o formadas pela mistura e solidifica\u00e7\u00e3o de diferentes elementos sem sofrer rea\u00e7\u00e3o qu\u00edmica. Bem, essa foi apenas uma &#8230; <a title=\"O a\u00e7o \u00e9 um composto? (+3 fatos para saber)\" class=\"read-more\" href=\"https:\/\/chemuza.org\/pt\/o-aco-e-um-composto\/\" aria-label=\"Mais em O a\u00e7o \u00e9 um composto? (+3 fatos para saber)\">Ler mais<\/a><\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[12],"tags":[],"class_list":["post-668","post","type-post","status-publish","format-standard","hentry","category-estrutura-de-lewis"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v21.4 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>O a\u00e7o \u00e9 um composto? (+3 fatos para saber) - Chemuza<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/chemuza.org\/pt\/o-aco-e-um-composto\/\" \/>\n<meta property=\"og:locale\" content=\"pt_PT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"O a\u00e7o \u00e9 um composto? (+3 fatos para saber) - Chemuza\" \/>\n<meta property=\"og:description\" content=\"N\u00e3o, o a\u00e7o n\u00e3o \u00e9 um composto . O a\u00e7o \u00e9 uma liga que \u00e9 uma mistura de ferro e carbono , al\u00e9m de outros elementos como mangan\u00eas, cromo ou n\u00edquel. Ao contr\u00e1rio dos compostos, as ligas s\u00e3o formadas pela mistura e solidifica\u00e7\u00e3o de diferentes elementos sem sofrer rea\u00e7\u00e3o qu\u00edmica. Bem, essa foi apenas uma ... Ler mais\" \/>\n<meta property=\"og:url\" content=\"https:\/\/chemuza.org\/pt\/o-aco-e-um-composto\/\" \/>\n<meta property=\"og:site_name\" content=\"Statorials\" \/>\n<meta property=\"article:published_time\" content=\"2023-07-21T23:59:41+00:00\" \/>\n<meta name=\"author\" content=\"Equipa editorial\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"Equipa editorial\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tempo estimado de leitura\" \/>\n\t<meta name=\"twitter:data2\" content=\"5 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\/\/chemuza.org\/pt\/o-aco-e-um-composto\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/chemuza.org\/pt\/o-aco-e-um-composto\/\"},\"author\":{\"name\":\"Equipa editorial\",\"@id\":\"https:\/\/chemuza.org\/pt\/#\/schema\/person\/23e8642a8a7581609ed515c93c5c8fee\"},\"headline\":\"O a\u00e7o \u00e9 um composto? (+3 fatos para saber)\",\"datePublished\":\"2023-07-21T23:59:41+00:00\",\"dateModified\":\"2023-07-21T23:59:41+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/chemuza.org\/pt\/o-aco-e-um-composto\/\"},\"wordCount\":924,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\/\/chemuza.org\/pt\/#organization\"},\"articleSection\":[\"Estrutura de lewis\"],\"inLanguage\":\"pt-PT\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\/\/chemuza.org\/pt\/o-aco-e-um-composto\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/chemuza.org\/pt\/o-aco-e-um-composto\/\",\"url\":\"https:\/\/chemuza.org\/pt\/o-aco-e-um-composto\/\",\"name\":\"O a\u00e7o \u00e9 um composto? (+3 fatos para saber) - Chemuza\",\"isPartOf\":{\"@id\":\"https:\/\/chemuza.org\/pt\/#website\"},\"datePublished\":\"2023-07-21T23:59:41+00:00\",\"dateModified\":\"2023-07-21T23:59:41+00:00\",\"breadcrumb\":{\"@id\":\"https:\/\/chemuza.org\/pt\/o-aco-e-um-composto\/#breadcrumb\"},\"inLanguage\":\"pt-PT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/chemuza.org\/pt\/o-aco-e-um-composto\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/chemuza.org\/pt\/o-aco-e-um-composto\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Lar\",\"item\":\"https:\/\/chemuza.org\/pt\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"O a\u00e7o \u00e9 um composto? (+3 fatos para saber)\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/chemuza.org\/pt\/#website\",\"url\":\"https:\/\/chemuza.org\/pt\/\",\"name\":\"Chemuza\",\"description\":\"Sua porta de entrada para a descoberta qu\u00edmica!\",\"publisher\":{\"@id\":\"https:\/\/chemuza.org\/pt\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/chemuza.org\/pt\/?s={search_term_string}\"},\"query-input\":\"required name=search_term_string\"}],\"inLanguage\":\"pt-PT\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/chemuza.org\/pt\/#organization\",\"name\":\"Chemuza\",\"url\":\"https:\/\/chemuza.org\/pt\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-PT\",\"@id\":\"https:\/\/chemuza.org\/pt\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/chemuza.org\/pt\/wp-content\/uploads\/2023\/10\/chemuza-logo.png\",\"contentUrl\":\"https:\/\/chemuza.org\/pt\/wp-content\/uploads\/2023\/10\/chemuza-logo.png\",\"width\":387,\"height\":70,\"caption\":\"Chemuza\"},\"image\":{\"@id\":\"https:\/\/chemuza.org\/pt\/#\/schema\/logo\/image\/\"}},{\"@type\":\"Person\",\"@id\":\"https:\/\/chemuza.org\/pt\/#\/schema\/person\/23e8642a8a7581609ed515c93c5c8fee\",\"name\":\"Equipa editorial\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-PT\",\"@id\":\"https:\/\/chemuza.org\/pt\/#\/schema\/person\/image\/\",\"url\":\"https:\/\/secure.gravatar.com\/avatar\/83f7322a09fc21cefea6640cea6759bbf64fa5d4c6b95e46e8d9efcd5e52a47a?s=96&d=mm&r=g\",\"contentUrl\":\"https:\/\/secure.gravatar.com\/avatar\/83f7322a09fc21cefea6640cea6759bbf64fa5d4c6b95e46e8d9efcd5e52a47a?s=96&d=mm&r=g\",\"caption\":\"Equipa editorial\"},\"sameAs\":[\"http:\/\/chemuza.org\/pt\"]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"O a\u00e7o \u00e9 um composto? (+3 fatos para saber) - Chemuza","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/chemuza.org\/pt\/o-aco-e-um-composto\/","og_locale":"pt_PT","og_type":"article","og_title":"O a\u00e7o \u00e9 um composto? (+3 fatos para saber) - Chemuza","og_description":"N\u00e3o, o a\u00e7o n\u00e3o \u00e9 um composto . O a\u00e7o \u00e9 uma liga que \u00e9 uma mistura de ferro e carbono , al\u00e9m de outros elementos como mangan\u00eas, cromo ou n\u00edquel. Ao contr\u00e1rio dos compostos, as ligas s\u00e3o formadas pela mistura e solidifica\u00e7\u00e3o de diferentes elementos sem sofrer rea\u00e7\u00e3o qu\u00edmica. Bem, essa foi apenas uma ... Ler mais","og_url":"https:\/\/chemuza.org\/pt\/o-aco-e-um-composto\/","og_site_name":"Statorials","article_published_time":"2023-07-21T23:59:41+00:00","author":"Equipa editorial","twitter_card":"summary_large_image","twitter_misc":{"Escrito por":"Equipa editorial","Tempo estimado de leitura":"5 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/chemuza.org\/pt\/o-aco-e-um-composto\/#article","isPartOf":{"@id":"https:\/\/chemuza.org\/pt\/o-aco-e-um-composto\/"},"author":{"name":"Equipa editorial","@id":"https:\/\/chemuza.org\/pt\/#\/schema\/person\/23e8642a8a7581609ed515c93c5c8fee"},"headline":"O a\u00e7o \u00e9 um composto? (+3 fatos para saber)","datePublished":"2023-07-21T23:59:41+00:00","dateModified":"2023-07-21T23:59:41+00:00","mainEntityOfPage":{"@id":"https:\/\/chemuza.org\/pt\/o-aco-e-um-composto\/"},"wordCount":924,"commentCount":0,"publisher":{"@id":"https:\/\/chemuza.org\/pt\/#organization"},"articleSection":["Estrutura de lewis"],"inLanguage":"pt-PT","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/chemuza.org\/pt\/o-aco-e-um-composto\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/chemuza.org\/pt\/o-aco-e-um-composto\/","url":"https:\/\/chemuza.org\/pt\/o-aco-e-um-composto\/","name":"O a\u00e7o \u00e9 um composto? (+3 fatos para saber) - Chemuza","isPartOf":{"@id":"https:\/\/chemuza.org\/pt\/#website"},"datePublished":"2023-07-21T23:59:41+00:00","dateModified":"2023-07-21T23:59:41+00:00","breadcrumb":{"@id":"https:\/\/chemuza.org\/pt\/o-aco-e-um-composto\/#breadcrumb"},"inLanguage":"pt-PT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/chemuza.org\/pt\/o-aco-e-um-composto\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/chemuza.org\/pt\/o-aco-e-um-composto\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Lar","item":"https:\/\/chemuza.org\/pt\/"},{"@type":"ListItem","position":2,"name":"O a\u00e7o \u00e9 um composto? (+3 fatos para saber)"}]},{"@type":"WebSite","@id":"https:\/\/chemuza.org\/pt\/#website","url":"https:\/\/chemuza.org\/pt\/","name":"Chemuza","description":"Sua porta de entrada para a descoberta qu\u00edmica!","publisher":{"@id":"https:\/\/chemuza.org\/pt\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/chemuza.org\/pt\/?s={search_term_string}"},"query-input":"required name=search_term_string"}],"inLanguage":"pt-PT"},{"@type":"Organization","@id":"https:\/\/chemuza.org\/pt\/#organization","name":"Chemuza","url":"https:\/\/chemuza.org\/pt\/","logo":{"@type":"ImageObject","inLanguage":"pt-PT","@id":"https:\/\/chemuza.org\/pt\/#\/schema\/logo\/image\/","url":"https:\/\/chemuza.org\/pt\/wp-content\/uploads\/2023\/10\/chemuza-logo.png","contentUrl":"https:\/\/chemuza.org\/pt\/wp-content\/uploads\/2023\/10\/chemuza-logo.png","width":387,"height":70,"caption":"Chemuza"},"image":{"@id":"https:\/\/chemuza.org\/pt\/#\/schema\/logo\/image\/"}},{"@type":"Person","@id":"https:\/\/chemuza.org\/pt\/#\/schema\/person\/23e8642a8a7581609ed515c93c5c8fee","name":"Equipa editorial","image":{"@type":"ImageObject","inLanguage":"pt-PT","@id":"https:\/\/chemuza.org\/pt\/#\/schema\/person\/image\/","url":"https:\/\/secure.gravatar.com\/avatar\/83f7322a09fc21cefea6640cea6759bbf64fa5d4c6b95e46e8d9efcd5e52a47a?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/83f7322a09fc21cefea6640cea6759bbf64fa5d4c6b95e46e8d9efcd5e52a47a?s=96&d=mm&r=g","caption":"Equipa editorial"},"sameAs":["http:\/\/chemuza.org\/pt"]}]}},"yoast_meta":{"yoast_wpseo_title":"","yoast_wpseo_metadesc":"","yoast_wpseo_canonical":""},"_links":{"self":[{"href":"https:\/\/chemuza.org\/pt\/wp-json\/wp\/v2\/posts\/668","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/chemuza.org\/pt\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/chemuza.org\/pt\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/chemuza.org\/pt\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/chemuza.org\/pt\/wp-json\/wp\/v2\/comments?post=668"}],"version-history":[{"count":0,"href":"https:\/\/chemuza.org\/pt\/wp-json\/wp\/v2\/posts\/668\/revisions"}],"wp:attachment":[{"href":"https:\/\/chemuza.org\/pt\/wp-json\/wp\/v2\/media?parent=668"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/chemuza.org\/pt\/wp-json\/wp\/v2\/categories?post=668"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/chemuza.org\/pt\/wp-json\/wp\/v2\/tags?post=668"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}