{"id":1092,"date":"2023-07-19T01:38:13","date_gmt":"2023-07-19T01:38:13","guid":{"rendered":"https:\/\/chemuza.org\/pt\/naoh-e-um-eletrolito-poderoso\/"},"modified":"2023-07-19T01:38:13","modified_gmt":"2023-07-19T01:38:13","slug":"naoh-e-um-eletrolito-poderoso","status":"publish","type":"post","link":"https:\/\/chemuza.org\/pt\/naoh-e-um-eletrolito-poderoso\/","title":{"rendered":"Por que o naoh \u00e9 um eletr\u00f3lito forte? (+3 coisas para saber)"},"content":{"rendered":"<p><strong>Sim, o hidr\u00f3xido de s\u00f3dio (NaOH) \u00e9 um <a href=\"https:\/\/en.wikipedia.org\/wiki\/Strong_electrolyte\" target=\"_blank\" rel=\"noopener\">eletr\u00f3lito poderoso<\/a> . O NaOH \u00e9 um eletr\u00f3lito poderoso porque se dissocia completamente em \u00edons s\u00f3dio (Na+) e \u00edons hidr\u00f3xido (OH-) quando dissolvido em \u00e1gua, resultando em uma alta concentra\u00e7\u00e3o de \u00edons e condutividade el\u00e9trica eficiente.<\/strong><\/p>\n<p> Bem, essa foi apenas uma resposta simples. Mas h\u00e1 mais algumas coisas que voc\u00ea deve saber sobre esse assunto que deixar\u00e3o seu conceito muito claro.<\/p>\n<p> Ent\u00e3o, vamos direto ao assunto. <\/p>\n<div class=\"inherit-container-width wp-block-group key is-layout-constrained wp-block-group-is-layout-constrained\">\n<div class=\"wp-block-group__inner-container\">\n<h3 class=\"wp-block-heading\"> <strong>Principais conclus\u00f5es: O NaOH \u00e9 um eletr\u00f3lito forte?<\/strong><\/h3>\n<ul>\n<li> O NaOH \u00e9 um eletr\u00f3lito poderoso porque se dissocia completamente em \u00edons s\u00f3dio (Na+) e \u00edons hidr\u00f3xido (OH-) quando dissolvido em \u00e1gua.<\/li>\n<li> O grau de dissocia\u00e7\u00e3o do NaOH \u00e9 significativamente maior do que o dos eletr\u00f3litos fracos.<\/li>\n<li> O NaOH encontra muitas aplica\u00e7\u00f5es como eletr\u00f3lito devido \u00e0 sua forte natureza alcalina e \u00e0 sua capacidade de se dissociar em \u00edons s\u00f3dio (Na+) e hidr\u00f3xido (OH-) quando dissolvido em \u00e1gua.<\/li>\n<\/ul>\n<\/div>\n<\/div>\n<h2 class=\"wp-block-heading\"> <strong>Explica\u00e7\u00e3o: Por que o NaOH \u00e9 um eletr\u00f3lito forte?<\/strong><\/h2>\n<p class=\"ans\"> <em>O NaOH (hidr\u00f3xido de s\u00f3dio) \u00e9 considerado um eletr\u00f3lito poderoso porque se dissocia quase completamente em seus \u00edons constituintes quando dissolvido em \u00e1gua. Isso resulta em uma alta concentra\u00e7\u00e3o de \u00edons na solu\u00e7\u00e3o, permitindo-lhe conduzir eletricidade de forma eficiente.<\/em><\/p>\n<p> Veja por que o NaOH \u00e9 um eletr\u00f3lito poderoso:<\/p>\n<ul>\n<li> <strong>Ioniza\u00e7\u00e3o Completa:<\/strong> Quando o NaOH se dissolve na \u00e1gua, ele sofre uma <a href=\"https:\/\/en.wikipedia.org\/wiki\/Dissociation_(chemistry)\" target=\"_blank\" rel=\"noopener\">rea\u00e7\u00e3o de dissocia\u00e7\u00e3o<\/a> onde se decomp\u00f5e em seus \u00edons constituintes. As mol\u00e9culas de hidr\u00f3xido de s\u00f3dio (NaOH) dissociam-se totalmente em \u00edons s\u00f3dio (Na+) e \u00edons hidr\u00f3xido (OH-) na <a href=\"https:\/\/chem.libretexts.org\/Courses\/University_of_Kentucky\/UK%3A_CHE_103_-_Chemistry_for_Allied_Health_(Soult)\/Chapters\/Chapter_7%3A_Solids_Liquids_and_Gases\/7.5%3A_Aqueous_Solutions\" target=\"_blank\" rel=\"noopener\">solu\u00e7\u00e3o aquosa<\/a> .<\/li>\n<\/ul>\n<p class=\"has-text-align-center\"> NaOH (s) \u2192 Na+ (aq) + OH- (aq)<\/p>\n<ul>\n<li> <strong>Alta concentra\u00e7\u00e3o i\u00f4nica:<\/strong> Como o NaOH se dissocia quase completamente em \u00edons, a concentra\u00e7\u00e3o de \u00edons na solu\u00e7\u00e3o \u00e9 alta. A disponibilidade de um grande n\u00famero de \u00edons permite um forte fluxo de carga el\u00e9trica, levando a uma condutividade el\u00e9trica eficiente.<\/li>\n<li> <strong>Condutividade:<\/strong> A capacidade de uma subst\u00e2ncia conduzir eletricidade depende da presen\u00e7a de part\u00edculas m\u00f3veis carregadas (\u00edons) na solu\u00e7\u00e3o. No caso do NaOH, devido \u00e0 ioniza\u00e7\u00e3o completa, um n\u00famero significativo de \u00edons fica dispon\u00edvel para transportar corrente el\u00e9trica.<\/li>\n<li> <strong>Propriedades \u00e1cido-base fortes:<\/strong> O NaOH \u00e9 uma base forte, o que significa que doa prontamente \u00edons hidr\u00f3xido (OH-) para a solu\u00e7\u00e3o. Esses \u00edons hidr\u00f3xido s\u00e3o respons\u00e1veis pela natureza alcalina da solu\u00e7\u00e3o e tamb\u00e9m contribuem para a sua condutividade.<\/li>\n<\/ul>\n<p> No geral, o alto grau de ioniza\u00e7\u00e3o e a presen\u00e7a de uma grande concentra\u00e7\u00e3o de \u00edons na solu\u00e7\u00e3o fazem do NaOH um eletr\u00f3lito poderoso. Em contraste, os eletr\u00f3litos fracos ionizam apenas parcialmente, resultando em uma menor concentra\u00e7\u00e3o de \u00edons e uma condutividade el\u00e9trica menos eficiente.<\/p>\n<h2 class=\"wp-block-heading\"> <strong>Grau de dissocia\u00e7\u00e3o de NaOH de eletr\u00f3litos fracos<\/strong><\/h2>\n<p class=\"ans\"> <em>O<\/em> <a href=\"https:\/\/chem.libretexts.org\/Bookshelves\/Physical_and_Theoretical_Chemistry_Textbook_Maps\/Physical_Chemistry_(Fleming)\/09%3A_Chemical_Equilibria\/9.05%3A_Degree_of_Dissociation\" target=\"_blank\" rel=\"noopener\"><em>grau de dissocia\u00e7\u00e3o<\/em><\/a> <em>do NaOH \u00e9 significativamente maior do que o dos eletr\u00f3litos fracos. O NaOH \u00e9 um eletr\u00f3lito forte, o que significa que se dissocia quase completamente em seus \u00edons constituintes (Na+ e OH-) quando dissolvido em \u00e1gua. Por outro lado, os eletr\u00f3litos fracos dissociam-se apenas parcialmente, resultando numa menor concentra\u00e7\u00e3o de i\u00f5es na solu\u00e7\u00e3o.<\/em><\/p>\n<p> Em solu\u00e7\u00f5es aquosas, eletr\u00f3litos fortes como o NaOH sofrem dissocia\u00e7\u00e3o quase completa em \u00edons. Quando o NaOH se dissolve na \u00e1gua, quase todas as mol\u00e9culas de NaOH se decomp\u00f5em em \u00edons s\u00f3dio (Na+) e \u00edons hidr\u00f3xido (OH-):<\/p>\n<p class=\"has-text-align-center\"> NaOH (s) \u2192 Na+ (aq) + OH- (aq)<\/p>\n<p> Este alto grau de dissocia\u00e7\u00e3o resulta em um grande n\u00famero de \u00edons presentes na solu\u00e7\u00e3o, levando a uma alta condutividade el\u00e9trica.<\/p>\n<p> Em contraste, os eletr\u00f3litos fracos dissociam-se apenas parcialmente em \u00edons. Isso significa que apenas uma fra\u00e7\u00e3o das mol\u00e9culas fracas do eletr\u00f3lito forma \u00edons na solu\u00e7\u00e3o. Como resultado, a concentra\u00e7\u00e3o de \u00edons na solu\u00e7\u00e3o \u00e9 muito menor do que a de eletr\u00f3litos fortes como o NaOH.<\/p>\n<p> Portanto, a condutividade el\u00e9trica dos eletr\u00f3litos fracos \u00e9 menor que a dos eletr\u00f3litos fortes. Exemplos de eletr\u00f3litos fracos incluem \u00e1cido ac\u00e9tico ( <a href=\"https:\/\/pubchem.ncbi.nlm.nih.gov\/compound\/Acetic-Acid\" target=\"_blank\" rel=\"noopener\">CH3COOH<\/a> ) e am\u00f4nia (NH3), que se dissociam parcialmente em seus respectivos \u00edons na \u00e1gua.<\/p>\n<h2 class=\"wp-block-heading\"> <strong>Aplica\u00e7\u00f5es nas quais o NaOH \u00e9 usado como eletr\u00f3lito<\/strong><\/h2>\n<p> O hidr\u00f3xido de s\u00f3dio (NaOH) encontra muitas aplica\u00e7\u00f5es como eletr\u00f3lito devido \u00e0 sua forte natureza alcalina e \u00e0 sua capacidade de se dissociar em \u00edons s\u00f3dio (Na+) e hidr\u00f3xido (OH-) quando dissolvido em \u00e1gua. Algumas aplica\u00e7\u00f5es comuns incluem:<\/p>\n<ol>\n<li> <strong>Galvanoplastia:<\/strong> O NaOH \u00e9 usado em v\u00e1rios processos de galvanoplastia como eletr\u00f3lito para depositar metais como cobre, zinco e n\u00edquel em substratos. A solu\u00e7\u00e3o de NaOH ajuda a fornecer as condi\u00e7\u00f5es alcalinas necess\u00e1rias e facilita o fluxo de \u00edons met\u00e1licos para o revestimento.<\/li>\n<li> <strong>Eletr\u00f3lito da bateria:<\/strong> O NaOH \u00e9 usado em certos tipos de baterias, como as baterias de n\u00edquel-hidreto met\u00e1lico (NiMH), onde atua como um eletr\u00f3lito facilitando o fluxo de \u00edons carregados durante as rea\u00e7\u00f5es eletroqu\u00edmicas.<\/li>\n<li> <strong>Limpeza Eletrol\u00edtica:<\/strong> O NaOH \u00e9 usado em processos de limpeza eletrol\u00edtica para remover contaminantes e dep\u00f3sitos de metais e outras superf\u00edcies. A solu\u00e7\u00e3o alcalina ajuda a quebrar a mat\u00e9ria org\u00e2nica e facilita o processo de limpeza.<\/li>\n<li> <strong>Extra\u00e7\u00e3o de alum\u00ednio:<\/strong> No <a href=\"https:\/\/en.wikipedia.org\/wiki\/Bayer_process\" target=\"_blank\" rel=\"noopener\">processo Bayer<\/a> , o NaOH \u00e9 usado para extrair \u00f3xido de alum\u00ednio do min\u00e9rio de bauxita. Ele reage com o \u00f3xido de alum\u00ednio para formar aluminato de s\u00f3dio sol\u00favel, que pode ent\u00e3o ser processado para obter alum\u00ednio met\u00e1lico.<\/li>\n<li> <strong>Fabrica\u00e7\u00e3o Qu\u00edmica:<\/strong> O NaOH \u00e9 um reagente crucial em v\u00e1rios processos qu\u00edmicos, incluindo a produ\u00e7\u00e3o de sab\u00f5es, detergentes e outros compostos org\u00e2nicos.<\/li>\n<li> <strong>Tratamento de \u00c1gua:<\/strong> Nas esta\u00e7\u00f5es de tratamento de \u00e1gua, o NaOH \u00e9 usado para ajustar os n\u00edveis de pH e neutralizar a \u00e1gua \u00e1cida. Tamb\u00e9m auxilia na remo\u00e7\u00e3o de metais pesados por meio de rea\u00e7\u00f5es de precipita\u00e7\u00e3o.<\/li>\n<li> <strong>Ind\u00fastria de Papel e Celulose:<\/strong> O NaOH \u00e9 usado em processos de polpa\u00e7\u00e3o e branqueamento para quebrar a lignina presente em cavacos de madeira e para branquear a celulose.<\/li>\n<li> <strong>Ind\u00fastria t\u00eaxtil:<\/strong> O NaOH \u00e9 utilizado na merceriza\u00e7\u00e3o, processo que confere maior resist\u00eancia e brilho \u00e0s fibras de algod\u00e3o.<\/li>\n<\/ol>\n<h3 class=\"wp-block-heading\"> <strong>Leitura adicional<\/strong><\/h3>\n<p> <a href=\"https:\/\/chemuza.org\/pt\/amonia-nh3-e-um-eletrolito-forte-ou-fraco\/\">O NH3 (am\u00f4nia) \u00e9 um eletr\u00f3lito forte ou fraco?<br \/><\/a> <a href=\"https:\/\/chemuza.org\/pt\/hf-e-um-eletrolito-poderoso\/\">O HF \u00e9 um eletr\u00f3lito poderoso?<br \/><\/a> <a href=\"https:\/\/chemuza.org\/pt\/o-etanol-c2h5oh-e-um-eletrolito\/\">O etanol (C2H5OH) \u00e9 um eletr\u00f3lito?<br \/><\/a> <a href=\"https:\/\/chemuza.org\/pt\/o-volume-e-uma-propriedade-fisica-ou-quimica\/\">O volume \u00e9 uma propriedade f\u00edsica ou qu\u00edmica?<br \/><\/a> <a href=\"https:\/\/chemuza.org\/pt\/a-maleabilidade-e-uma-propriedade-fisica-ou-quimica\/\">A maleabilidade \u00e9 uma propriedade f\u00edsica ou qu\u00edmica?<\/a><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Sim, o hidr\u00f3xido de s\u00f3dio (NaOH) \u00e9 um eletr\u00f3lito poderoso . O NaOH \u00e9 um eletr\u00f3lito poderoso porque se dissocia completamente em \u00edons s\u00f3dio (Na+) e \u00edons hidr\u00f3xido (OH-) quando dissolvido em \u00e1gua, resultando em uma alta concentra\u00e7\u00e3o de \u00edons e condutividade el\u00e9trica eficiente. Bem, essa foi apenas uma resposta simples. Mas h\u00e1 mais algumas &#8230; <a title=\"Por que o naoh \u00e9 um eletr\u00f3lito forte? (+3 coisas para saber)\" class=\"read-more\" href=\"https:\/\/chemuza.org\/pt\/naoh-e-um-eletrolito-poderoso\/\" aria-label=\"Mais em Por que o naoh \u00e9 um eletr\u00f3lito forte? (+3 coisas para saber)\">Ler mais<\/a><\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[12],"tags":[],"class_list":["post-1092","post","type-post","status-publish","format-standard","hentry","category-estrutura-de-lewis"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v21.4 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Por que o NaOH \u00e9 um eletr\u00f3lito forte? (+3 coisas para saber) - Chemuza<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/chemuza.org\/pt\/naoh-e-um-eletrolito-poderoso\/\" \/>\n<meta property=\"og:locale\" content=\"pt_PT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Por que o NaOH \u00e9 um eletr\u00f3lito forte? (+3 coisas para saber) - Chemuza\" \/>\n<meta property=\"og:description\" content=\"Sim, o hidr\u00f3xido de s\u00f3dio (NaOH) \u00e9 um eletr\u00f3lito poderoso . O NaOH \u00e9 um eletr\u00f3lito poderoso porque se dissocia completamente em \u00edons s\u00f3dio (Na+) e \u00edons hidr\u00f3xido (OH-) quando dissolvido em \u00e1gua, resultando em uma alta concentra\u00e7\u00e3o de \u00edons e condutividade el\u00e9trica eficiente. Bem, essa foi apenas uma resposta simples. Mas h\u00e1 mais algumas ... Ler mais\" \/>\n<meta property=\"og:url\" content=\"https:\/\/chemuza.org\/pt\/naoh-e-um-eletrolito-poderoso\/\" \/>\n<meta property=\"og:site_name\" content=\"Statorials\" \/>\n<meta property=\"article:published_time\" content=\"2023-07-19T01:38:13+00:00\" \/>\n<meta name=\"author\" content=\"Equipa editorial\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"Equipa editorial\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tempo estimado de leitura\" \/>\n\t<meta name=\"twitter:data2\" content=\"6 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\/\/chemuza.org\/pt\/naoh-e-um-eletrolito-poderoso\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/chemuza.org\/pt\/naoh-e-um-eletrolito-poderoso\/\"},\"author\":{\"name\":\"Equipa editorial\",\"@id\":\"https:\/\/chemuza.org\/pt\/#\/schema\/person\/23e8642a8a7581609ed515c93c5c8fee\"},\"headline\":\"Por que o naoh \u00e9 um eletr\u00f3lito forte? (+3 coisas para saber)\",\"datePublished\":\"2023-07-19T01:38:13+00:00\",\"dateModified\":\"2023-07-19T01:38:13+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/chemuza.org\/pt\/naoh-e-um-eletrolito-poderoso\/\"},\"wordCount\":1123,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\/\/chemuza.org\/pt\/#organization\"},\"articleSection\":[\"Estrutura de lewis\"],\"inLanguage\":\"pt-PT\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\/\/chemuza.org\/pt\/naoh-e-um-eletrolito-poderoso\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/chemuza.org\/pt\/naoh-e-um-eletrolito-poderoso\/\",\"url\":\"https:\/\/chemuza.org\/pt\/naoh-e-um-eletrolito-poderoso\/\",\"name\":\"Por que o NaOH \u00e9 um eletr\u00f3lito forte? (+3 coisas para saber) - Chemuza\",\"isPartOf\":{\"@id\":\"https:\/\/chemuza.org\/pt\/#website\"},\"datePublished\":\"2023-07-19T01:38:13+00:00\",\"dateModified\":\"2023-07-19T01:38:13+00:00\",\"breadcrumb\":{\"@id\":\"https:\/\/chemuza.org\/pt\/naoh-e-um-eletrolito-poderoso\/#breadcrumb\"},\"inLanguage\":\"pt-PT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/chemuza.org\/pt\/naoh-e-um-eletrolito-poderoso\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/chemuza.org\/pt\/naoh-e-um-eletrolito-poderoso\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Lar\",\"item\":\"https:\/\/chemuza.org\/pt\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Por que o naoh \u00e9 um eletr\u00f3lito forte? (+3 coisas para saber)\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/chemuza.org\/pt\/#website\",\"url\":\"https:\/\/chemuza.org\/pt\/\",\"name\":\"Chemuza\",\"description\":\"Sua porta de entrada para a descoberta qu\u00edmica!\",\"publisher\":{\"@id\":\"https:\/\/chemuza.org\/pt\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/chemuza.org\/pt\/?s={search_term_string}\"},\"query-input\":\"required name=search_term_string\"}],\"inLanguage\":\"pt-PT\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/chemuza.org\/pt\/#organization\",\"name\":\"Chemuza\",\"url\":\"https:\/\/chemuza.org\/pt\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-PT\",\"@id\":\"https:\/\/chemuza.org\/pt\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/chemuza.org\/pt\/wp-content\/uploads\/2023\/10\/chemuza-logo.png\",\"contentUrl\":\"https:\/\/chemuza.org\/pt\/wp-content\/uploads\/2023\/10\/chemuza-logo.png\",\"width\":387,\"height\":70,\"caption\":\"Chemuza\"},\"image\":{\"@id\":\"https:\/\/chemuza.org\/pt\/#\/schema\/logo\/image\/\"}},{\"@type\":\"Person\",\"@id\":\"https:\/\/chemuza.org\/pt\/#\/schema\/person\/23e8642a8a7581609ed515c93c5c8fee\",\"name\":\"Equipa editorial\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-PT\",\"@id\":\"https:\/\/chemuza.org\/pt\/#\/schema\/person\/image\/\",\"url\":\"https:\/\/secure.gravatar.com\/avatar\/83f7322a09fc21cefea6640cea6759bbf64fa5d4c6b95e46e8d9efcd5e52a47a?s=96&d=mm&r=g\",\"contentUrl\":\"https:\/\/secure.gravatar.com\/avatar\/83f7322a09fc21cefea6640cea6759bbf64fa5d4c6b95e46e8d9efcd5e52a47a?s=96&d=mm&r=g\",\"caption\":\"Equipa editorial\"},\"sameAs\":[\"http:\/\/chemuza.org\/pt\"]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Por que o NaOH \u00e9 um eletr\u00f3lito forte? (+3 coisas para saber) - Chemuza","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/chemuza.org\/pt\/naoh-e-um-eletrolito-poderoso\/","og_locale":"pt_PT","og_type":"article","og_title":"Por que o NaOH \u00e9 um eletr\u00f3lito forte? (+3 coisas para saber) - Chemuza","og_description":"Sim, o hidr\u00f3xido de s\u00f3dio (NaOH) \u00e9 um eletr\u00f3lito poderoso . O NaOH \u00e9 um eletr\u00f3lito poderoso porque se dissocia completamente em \u00edons s\u00f3dio (Na+) e \u00edons hidr\u00f3xido (OH-) quando dissolvido em \u00e1gua, resultando em uma alta concentra\u00e7\u00e3o de \u00edons e condutividade el\u00e9trica eficiente. Bem, essa foi apenas uma resposta simples. Mas h\u00e1 mais algumas ... Ler mais","og_url":"https:\/\/chemuza.org\/pt\/naoh-e-um-eletrolito-poderoso\/","og_site_name":"Statorials","article_published_time":"2023-07-19T01:38:13+00:00","author":"Equipa editorial","twitter_card":"summary_large_image","twitter_misc":{"Escrito por":"Equipa editorial","Tempo estimado de leitura":"6 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/chemuza.org\/pt\/naoh-e-um-eletrolito-poderoso\/#article","isPartOf":{"@id":"https:\/\/chemuza.org\/pt\/naoh-e-um-eletrolito-poderoso\/"},"author":{"name":"Equipa editorial","@id":"https:\/\/chemuza.org\/pt\/#\/schema\/person\/23e8642a8a7581609ed515c93c5c8fee"},"headline":"Por que o naoh \u00e9 um eletr\u00f3lito forte? (+3 coisas para saber)","datePublished":"2023-07-19T01:38:13+00:00","dateModified":"2023-07-19T01:38:13+00:00","mainEntityOfPage":{"@id":"https:\/\/chemuza.org\/pt\/naoh-e-um-eletrolito-poderoso\/"},"wordCount":1123,"commentCount":0,"publisher":{"@id":"https:\/\/chemuza.org\/pt\/#organization"},"articleSection":["Estrutura de lewis"],"inLanguage":"pt-PT","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/chemuza.org\/pt\/naoh-e-um-eletrolito-poderoso\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/chemuza.org\/pt\/naoh-e-um-eletrolito-poderoso\/","url":"https:\/\/chemuza.org\/pt\/naoh-e-um-eletrolito-poderoso\/","name":"Por que o NaOH \u00e9 um eletr\u00f3lito forte? (+3 coisas para saber) - Chemuza","isPartOf":{"@id":"https:\/\/chemuza.org\/pt\/#website"},"datePublished":"2023-07-19T01:38:13+00:00","dateModified":"2023-07-19T01:38:13+00:00","breadcrumb":{"@id":"https:\/\/chemuza.org\/pt\/naoh-e-um-eletrolito-poderoso\/#breadcrumb"},"inLanguage":"pt-PT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/chemuza.org\/pt\/naoh-e-um-eletrolito-poderoso\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/chemuza.org\/pt\/naoh-e-um-eletrolito-poderoso\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Lar","item":"https:\/\/chemuza.org\/pt\/"},{"@type":"ListItem","position":2,"name":"Por que o naoh \u00e9 um eletr\u00f3lito forte? (+3 coisas para saber)"}]},{"@type":"WebSite","@id":"https:\/\/chemuza.org\/pt\/#website","url":"https:\/\/chemuza.org\/pt\/","name":"Chemuza","description":"Sua porta de entrada para a descoberta qu\u00edmica!","publisher":{"@id":"https:\/\/chemuza.org\/pt\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/chemuza.org\/pt\/?s={search_term_string}"},"query-input":"required name=search_term_string"}],"inLanguage":"pt-PT"},{"@type":"Organization","@id":"https:\/\/chemuza.org\/pt\/#organization","name":"Chemuza","url":"https:\/\/chemuza.org\/pt\/","logo":{"@type":"ImageObject","inLanguage":"pt-PT","@id":"https:\/\/chemuza.org\/pt\/#\/schema\/logo\/image\/","url":"https:\/\/chemuza.org\/pt\/wp-content\/uploads\/2023\/10\/chemuza-logo.png","contentUrl":"https:\/\/chemuza.org\/pt\/wp-content\/uploads\/2023\/10\/chemuza-logo.png","width":387,"height":70,"caption":"Chemuza"},"image":{"@id":"https:\/\/chemuza.org\/pt\/#\/schema\/logo\/image\/"}},{"@type":"Person","@id":"https:\/\/chemuza.org\/pt\/#\/schema\/person\/23e8642a8a7581609ed515c93c5c8fee","name":"Equipa editorial","image":{"@type":"ImageObject","inLanguage":"pt-PT","@id":"https:\/\/chemuza.org\/pt\/#\/schema\/person\/image\/","url":"https:\/\/secure.gravatar.com\/avatar\/83f7322a09fc21cefea6640cea6759bbf64fa5d4c6b95e46e8d9efcd5e52a47a?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/83f7322a09fc21cefea6640cea6759bbf64fa5d4c6b95e46e8d9efcd5e52a47a?s=96&d=mm&r=g","caption":"Equipa editorial"},"sameAs":["http:\/\/chemuza.org\/pt"]}]}},"yoast_meta":{"yoast_wpseo_title":"","yoast_wpseo_metadesc":"","yoast_wpseo_canonical":""},"_links":{"self":[{"href":"https:\/\/chemuza.org\/pt\/wp-json\/wp\/v2\/posts\/1092","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/chemuza.org\/pt\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/chemuza.org\/pt\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/chemuza.org\/pt\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/chemuza.org\/pt\/wp-json\/wp\/v2\/comments?post=1092"}],"version-history":[{"count":0,"href":"https:\/\/chemuza.org\/pt\/wp-json\/wp\/v2\/posts\/1092\/revisions"}],"wp:attachment":[{"href":"https:\/\/chemuza.org\/pt\/wp-json\/wp\/v2\/media?parent=1092"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/chemuza.org\/pt\/wp-json\/wp\/v2\/categories?post=1092"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/chemuza.org\/pt\/wp-json\/wp\/v2\/tags?post=1092"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}